{"id":17361,"date":"2025-08-21T12:49:24","date_gmt":"2025-08-21T10:49:24","guid":{"rendered":"https:\/\/euniv.eu\/?p=17361"},"modified":"2025-08-21T12:49:26","modified_gmt":"2025-08-21T10:49:26","slug":"deposito-de-tesis-doctoral","status":"publish","type":"post","link":"https:\/\/euniv.eu\/es\/deposito-de-tesis-doctoral\/","title":{"rendered":"Dep\u00f3sito de tesis doctoral"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En fecha 20 de agosto de 2025 ha sido depositada en el Registro General de la Universitas Europaea IMF la memoria de tesis doctoral elaborada por el doctorando Rodrigo Cabedo, bajo la tutela acad\u00e9mica del Dr. Jes\u00fas M. Pruj\u00e0. La tesis se titula <em>\u201cLa ense\u00f1anza superior universitaria de Ciencias Empresariales en los Principados de Andorra y Catalu\u00f1a en el Siglo XXI\u201d<\/em>, y pertenece a la L\u00ednea de Investigaci\u00f3n Doctoral sobre <em>\u201cLos estudios universitarios en los principados de Andorra y Catalu\u00f1a: an\u00e1lisis comparativo y evolutivo de la oferta y la demanda (2000-2025)\u201d<\/em>, organizada por el Instituto Universitario Alma Mater y coordinada por el propio Dr. Pruj\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la normativa vigente de la Escuela de Doctorado J. H. Newman de la eUniv, la Comisi\u00f3n de Doctorado deber\u00e1 resolver en su sesi\u00f3n del mes de septiembre la ordenaci\u00f3n de los procedimientos vinculados a la presentaci\u00f3n y defensa en los plazos establecidos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/euniv.eu\/wp-content\/uploads\/2024\/12\/Defensa-Tesi-2-2.jpg\" alt=\"\" class=\"wp-image-14068\" srcset=\"https:\/\/euniv.eu\/wp-content\/uploads\/2024\/12\/Defensa-Tesi-2-2.jpg 480w, https:\/\/euniv.eu\/wp-content\/uploads\/2024\/12\/Defensa-Tesi-2-2-225x300.jpg 225w, https:\/\/euniv.eu\/wp-content\/uploads\/2024\/12\/Defensa-Tesi-2-2-300x400.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En fecha 20 de agosto de 2025 ha sido depositada en el Registro General de la Universitas Europaea IMF la memoria de tesis doctoral elaborada por el doctorando Rodrigo Cabedo, bajo la tutela acad\u00e9mica del Dr. Jes\u00fas M. Pruj\u00e0. La tesis se titula \u201cLa ense\u00f1anza superior universitaria de Ciencias Empresariales en los Principados de Andorra y Catalu\u00f1a en el Siglo XXI\u201d<\/p>\n","protected":false},"author":2,"featured_media":14068,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-17361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","with-featured-image"],"featured_image_src":"https:\/\/euniv.eu\/wp-content\/uploads\/2024\/12\/Defensa-Tesi-2-2-480x400.jpg","featured_image_src_square":"https:\/\/euniv.eu\/wp-content\/uploads\/2024\/12\/Defensa-Tesi-2-2-480x600.jpg","author_info":{"display_name":"admin_euniv","author_link":"https:\/\/euniv.eu\/es\/author\/admin_euniv\/"},"_links":{"self":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/17361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/comments?post=17361"}],"version-history":[{"count":2,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/17361\/revisions"}],"predecessor-version":[{"id":17384,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/17361\/revisions\/17384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/media\/14068"}],"wp:attachment":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/media?parent=17361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/categories?post=17361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/tags?post=17361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}