{"id":18882,"date":"2025-11-17T14:21:58","date_gmt":"2025-11-17T13:21:58","guid":{"rendered":"https:\/\/euniv.eu\/?p=18882"},"modified":"2025-11-17T14:22:01","modified_gmt":"2025-11-17T13:22:01","slug":"la-euniv-participa-en-el-eqaf-2025-de-budapest-con-la-presencia-de-su-director-de-calidad","status":"publish","type":"post","link":"https:\/\/euniv.eu\/es\/la-euniv-participa-en-el-eqaf-2025-de-budapest-con-la-presencia-de-su-director-de-calidad\/","title":{"rendered":"La eUniv participa en el EQAF 2025 de Budapest con la presencia de su director de calidad"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La <strong>Universidad Europea (eUniv)<\/strong> ha estado presente en el <strong><a href=\"https:\/\/www.eua.eu\/events\/eua-events\/2025-european-quality-assurance-forum.html\" target=\"_blank\" rel=\"noreferrer noopener\">Foro Europeo para el Aseguramiento de la Calidad (EQAF)<\/a><\/strong> 2025, que se ha celebrado en la Corvinus University de Budapest (Hungr\u00eda) del 12 al 14 de noviembre, a trav\u00e9s de la participaci\u00f3n de su director de calidad, el Sr. Aleu Miret.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El foro, tal y como destaca la <a href=\"https:\/\/www.aqua.ad\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Agencia de Calidad Andorrana (AQUA)<\/strong><\/a>, es una plataforma clave para el debate y el intercambio de buenas pr\u00e1cticas entre agencias, universidades, asociaciones y otras entidades internacionales implicadas en el aseguramiento de la calidad en la educaci\u00f3n superior. Este a\u00f1o, el tema central es <em>\u00abEl aseguramiento de la calidad en tiempos de crisis: garantizar la estabilidad, la autonom\u00eda y la cooperaci\u00f3n internacional en la educaci\u00f3n superior\u00bb<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la participaci\u00f3n del Sr. Miret en este encuentro,<strong> la eUniv refuerza su compromiso con la calidad, la resiliencia institucional y la cooperaci\u00f3n internacional<\/strong>, contribuyendo activamente a los debates sobre c\u00f3mo preservar los valores acad\u00e9micos y fortalecer los sistemas de aseguramiento de la calidad incluso en contextos de incertidumbre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/euniv.eu\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-17-at-13.02.23-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-18885\" srcset=\"https:\/\/euniv.eu\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-17-at-13.02.23-1-1024x768.jpeg 1024w, https:\/\/euniv.eu\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-17-at-13.02.23-1-300x225.jpeg 300w, https:\/\/euniv.eu\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-17-at-13.02.23-1-768x576.jpeg 768w, https:\/\/euniv.eu\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-17-at-13.02.23-1-1200x900.jpeg 1200w, https:\/\/euniv.eu\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-17-at-13.02.23-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Europea (eUniv) ha estado presente en el Foro Europeo para el Aseguramiento de la Calidad (EQAF) 2025, que se ha celebrado en la Corvinus University de Budapest (Hungr\u00eda) del 12 al 14 de noviembre, a trav\u00e9s de la participaci\u00f3n de su director de calidad, el Sr. Aleu Miret.<\/p>\n","protected":false},"author":2,"featured_media":18885,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-18882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","with-featured-image"],"featured_image_src":"https:\/\/euniv.eu\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-17-at-13.02.23-1-600x400.jpeg","featured_image_src_square":"https:\/\/euniv.eu\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-17-at-13.02.23-1-600x600.jpeg","author_info":{"display_name":"admin_euniv","author_link":"https:\/\/euniv.eu\/es\/author\/admin_euniv\/"},"_links":{"self":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/18882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/comments?post=18882"}],"version-history":[{"count":1,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/18882\/revisions"}],"predecessor-version":[{"id":18886,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/18882\/revisions\/18886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/media\/18885"}],"wp:attachment":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/media?parent=18882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/categories?post=18882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/tags?post=18882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}