{"id":20682,"date":"2026-05-14T16:38:00","date_gmt":"2026-05-14T14:38:00","guid":{"rendered":"https:\/\/euniv.eu\/?p=20682"},"modified":"2026-09-01T16:40:07","modified_gmt":"2026-09-01T14:40:07","slug":"nueva-publicacion-de-investigacion-de-la-escuela-de-doctorado","status":"publish","type":"post","link":"https:\/\/euniv.eu\/es\/nueva-publicacion-de-investigacion-de-la-escuela-de-doctorado\/","title":{"rendered":"Nueva publicaci\u00f3n de investigaci\u00f3n de la Escuela de Doctorado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Dr. Antonio Serrano, profesor de Derecho Mercantil de la Universidad Rey Juan Carlos de Madrid, ha publicado el trabajo de investigaci\u00f3n realizado durante su estancia como investigador visitante en la Escuela de Doctorado J. H. Newman de la eUniv. El trabajo, titulado \u201c<em>La automatizaci\u00f3n de la justicia digital: ODRS, Inteligencia Artificial y la redefinici\u00f3n transnacional de las garant\u00edas procesales<\/em>\u201d, forma parte del libro \u201c<em>\u00bfJusticia algor\u00edtmica?: Inteligencia Artificial y m\u00e9todos adecuados de gesti\u00f3n de conflictos tras la Ley Org\u00e1nica 1\/2025<\/em>\u201d (cap\u00edtulo V), coordinado por las profesoras Marta Gonzalo y Mar\u00eda del Carmen Cazorla y publicado por la Editorial Aranzadi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su investigaci\u00f3n, el Dr. Serrano analiza la transici\u00f3n de la justicia digital hacia un modelo de justicia algor\u00edtmica y el impacto de la inteligencia artificial en las garant\u00edas procesales continentales. Se examina la tensi\u00f3n entre la eficiencia t\u00e9cnica y principios fundamentales como la tutela judicial efectiva, el derecho de defensa y la motivaci\u00f3n de las resoluciones, amenazados por la opacidad de los sistemas de \u201ccaja negra\u201d. El estudio aborda el marco normativo de la UE, destacando el Reglamento de Inteligencia Artificial y la Ley de Servicios Digitales como vectores que imponen la supervisi\u00f3n humana y la transparencia. Asimismo, se eval\u00faan los l\u00edmites del orden p\u00fablico internacional bajo la Convenci\u00f3n de Nueva York ante laudos automatizados y se concluye analizando el efecto Bruselas como motor de un est\u00e1ndar \u00e9tico y probatorio global que supedita la innovaci\u00f3n al Estado de Derecho.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"591\" src=\"https:\/\/euniv.eu\/wp-content\/uploads\/2026\/09\/Pg-WEB-3.jpg\" alt=\"\" class=\"wp-image-20681\" srcset=\"https:\/\/euniv.eu\/wp-content\/uploads\/2026\/09\/Pg-WEB-3.jpg 591w, https:\/\/euniv.eu\/wp-content\/uploads\/2026\/09\/Pg-WEB-3-300x300.jpg 300w, https:\/\/euniv.eu\/wp-content\/uploads\/2026\/09\/Pg-WEB-3-150x150.jpg 150w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Dr. Antonio Serrano, profesor de Derecho Mercantil de la Universidad Rey Juan Carlos de Madrid, ha publicado el trabajo de investigaci\u00f3n realizado durante su estancia como investigador visitante en la Escuela de Doctorado J. H. Newman de la eUniv<\/p>\n","protected":false},"author":2,"featured_media":20681,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-20682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","with-featured-image"],"featured_image_src":"https:\/\/euniv.eu\/wp-content\/uploads\/2026\/09\/Pg-WEB-3-591x400.jpg","featured_image_src_square":"https:\/\/euniv.eu\/wp-content\/uploads\/2026\/09\/Pg-WEB-3.jpg","author_info":{"display_name":"admin_euniv","author_link":"https:\/\/euniv.eu\/es\/author\/admin_euniv\/"},"_links":{"self":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/20682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/comments?post=20682"}],"version-history":[{"count":1,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/20682\/revisions"}],"predecessor-version":[{"id":20684,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/20682\/revisions\/20684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/media\/20681"}],"wp:attachment":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/media?parent=20682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/categories?post=20682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/tags?post=20682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}