{"id":9645,"date":"2023-10-11T11:06:21","date_gmt":"2023-10-11T11:06:21","guid":{"rendered":"https:\/\/euniv.eu\/?p=9645"},"modified":"2023-10-15T20:47:57","modified_gmt":"2023-10-15T20:47:57","slug":"la-ix-edicio-del-symposium-un-exito","status":"publish","type":"post","link":"https:\/\/euniv.eu\/es\/la-ix-edicio-del-symposium-un-exito\/","title":{"rendered":"El OEC de la eUniv y ESRP colabora en la IX edici\u00f3 del Symposium"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por segundo a\u00f1o consecutivo, el <a aria-label=\"OEC (Observatorio Europeo de la Comunicaci\u00f3n) (opens in a new tab)\" href=\"https:\/\/euniv.eu\/es\/investigacion\/observatorio-europeo-de-la-comunicacion\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">OEC (Observatorio Europeo de la Comunicaci\u00f3n)<\/a> de la <a aria-label=\"eUniv (opens in a new tab)\" href=\"https:\/\/euniv.eu\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">eUniv<\/a> y <a aria-label=\"ESRP (opens in a new tab)\" href=\"https:\/\/www.esrp.net\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">ESRP<\/a> ha colaborado con el <a aria-label=\"Symposium Grafica (opens in a new tab)\" href=\"https:\/\/www.symposiumgrafica.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">Symposium Grafica<\/a>. Este patrocinio se enmarca dentro de los objetivos del centro de investigaci\u00f3n, como es el hecho de \u00a0promover las actividades de investigaci\u00f3n cient\u00edfica y doctoral en los \u00e1mbitos espec\u00edficos de la Comunicaci\u00f3n, la Publicidad, las Relaciones P\u00fablicas y el Marketing.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El noveno encuentro internacional de investigaci\u00f3n en dise\u00f1o gr\u00e1fico y publicidad <strong>se celebr\u00f3 los d\u00edas 6, 7 y 8 de septiembre de 2023 en LISBOA (Portugal)<\/strong>. En esta edici\u00f3n el anfitri\u00f3n del symposium se celebr\u00f3 en el <a aria-label=\"TGRAF Centro de Estudios en Tecnolog\u00edas Gr\u00e1ficas del ISEC Lisboa (opens in a new tab)\" href=\"https:\/\/www.tgraf-iseclisboa.online\/index.php\/2521-2\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">TGRAF Centro de Estudios en Tecnolog\u00edas Gr\u00e1ficas del ISEC Lisboa<\/a> \u00b7 Instituto Superior de Educaci\u00f3n y Ciencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Symposium de este a\u00f1o contar\u00e1 con <strong>ponencias orales, online y en formato<\/strong> p\u00f3ster en relaci\u00f3n al dise\u00f1o gr\u00e1fico y la creatividad publicitaria a cargo de varios ponentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El d\u00eda 6 de septiembre se realiz\u00f3 la inauguraci\u00f3n, presentaci\u00f3n y explicaci\u00f3n de los objetivos de la novena edici\u00f3n y, los d\u00edas 7 y 8 de septiembre, se llevaron a cabo varias tablas que configuraban el cuerpo principal del encuentro. En los siguientes enlaces se pueden recuperar las intervenciones de los ponentes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7 de septiembre:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Investigaci\u00f3n 1. <a href=\"https:\/\/youtu.be\/vLl6vomp67k\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/vLl6vomp67k<\/a><\/li>\n\n\n\n<li>Did\u00e1ctica 1. <a href=\"https:\/\/youtu.be\/k3YEcPL-qUg\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/k3YEcPL-qUg<\/a><\/li>\n\n\n\n<li>Investigaci\u00f3n 2. <a href=\"https:\/\/youtu.be\/HvzdEctiteE\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/HvzdEctiteE<\/a><\/li>\n\n\n\n<li>Conferencia central. <a href=\"https:\/\/youtu.be\/UeHvggoXI9Y\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/UeHvggoXI9Y<\/a><\/li>\n\n\n\n<li>Did\u00e1ctica 2. <a aria-label=\"https:\/\/youtu.be\/c4fRB89FCPw (opens in a new tab)\" href=\"https:\/\/youtu.be\/c4fRB89FCPw\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">https:\/\/youtu.be\/c4fRB89FCPw<\/a><\/li>\n\n\n\n<li>Investigaci\u00f3n 3. <a href=\"https:\/\/youtu.be\/TIp7cuzZtwI\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/TIp7cuzZtwI<\/a><\/li>\n\n\n\n<li>Workshop investigaci\u00f3n. <a href=\"https:\/\/youtu.be\/xgWr3_v6tuY\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/xgWr3_v6tuY<\/a><\/li>\n\n\n\n<li>P\u00f3sters. <a href=\"https:\/\/youtu.be\/mbeEJFMOoVA\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/mbeEJFMOoVA<\/a><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8 de septiembre:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>La profesi\u00f3n. <a href=\"https:\/\/youtu.be\/34YKpIvoHRM\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/34YKpIvoHRM<\/a><\/li>\n\n\n\n<li>La investigaci\u00f3n. <a href=\"https:\/\/youtu.be\/rHkX0F9c4Zw\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/rHkX0F9c4Zw<\/a><\/li>\n\n\n\n<li>Investigaci\u00f3n 4. <a href=\"https:\/\/youtu.be\/8qxo2BFZx7g\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/8qxo2BFZx7g<\/a><\/li>\n\n\n\n<li>Investigaci\u00f3n 5. <a href=\"https:\/\/youtu.be\/RUDeAFnHpTY\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/RUDeAFnHpTY<\/a><\/li>\n\n\n\n<li>Conclusiones y IX Symposium grafica. <a href=\"https:\/\/youtu.be\/mxd3sWm2wXU\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">https:\/\/youtu.be\/mxd3sWm2wXU<\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>La novena trobada internacional de recerca en disseny gr\u00e0fic i publicitat es va celebrar els dies 6, 7 i 8 de setembre de 2023 a LISBOA (Portugal)<\/p>\n","protected":false},"author":2,"featured_media":9640,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-9645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","with-featured-image"],"featured_image_src":"https:\/\/euniv.eu\/wp-content\/uploads\/2023\/10\/4f17e5f82a58522cd150110f14368e3a5a4ea34b.png","featured_image_src_square":"https:\/\/euniv.eu\/wp-content\/uploads\/2023\/10\/4f17e5f82a58522cd150110f14368e3a5a4ea34b.png","author_info":{"display_name":"admin_euniv","author_link":"https:\/\/euniv.eu\/es\/author\/admin_euniv\/"},"_links":{"self":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/9645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/comments?post=9645"}],"version-history":[{"count":3,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/9645\/revisions"}],"predecessor-version":[{"id":9666,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/posts\/9645\/revisions\/9666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/media\/9640"}],"wp:attachment":[{"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/media?parent=9645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/categories?post=9645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euniv.eu\/es\/wp-json\/wp\/v2\/tags?post=9645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}